{"id":3628,"date":"2026-07-10T23:49:19","date_gmt":"2026-07-10T23:49:19","guid":{"rendered":"https:\/\/cnnbra.com.br\/al\/blog\/2026\/07\/10\/ibovespa-avanca-quase-3-e-se-aproxima-dos-178-mil-pontos\/"},"modified":"2026-07-10T23:49:19","modified_gmt":"2026-07-10T23:49:19","slug":"ibovespa-avanca-quase-3-e-se-aproxima-dos-178-mil-pontos","status":"publish","type":"post","link":"https:\/\/cnnbra.com.br\/al\/blog\/2026\/07\/10\/ibovespa-avanca-quase-3-e-se-aproxima-dos-178-mil-pontos\/","title":{"rendered":"Ibovespa avan\u00e7a quase 3% e se aproxima dos 178 mil pontos"},"content":{"rendered":"<p>O Ibovespa registrou um expressivo crescimento de quase 3% nesta sexta-feira (10), atingindo 177.866,37 pontos, um marco que n\u00e3o era alcan\u00e7ado desde maio. O aumento foi impulsionado por dados de infla\u00e7\u00e3o que renovaram as expectativas de uma poss\u00edvel redu\u00e7\u00e3o na taxa Selic em agosto. Neste contexto, a bolsa acumulou uma alta de 2,18% na semana, consolidando-se como a terceira consecutiva com desempenho positivo.<\/p>\n<p>\\n<\/p>\n<p>O \u00cdndice Nacional de Pre\u00e7os ao Consumidor Amplo (IPCA) subiu apenas 0,16% em junho, ficando abaixo da previs\u00e3o de 0,31%. Essa leitura, considerada a mais baixa desde outubro, trouxe otimismo ao mercado, de acordo com an\u00e1lise do Bank of America. A expectativa de um corte de 0,25 ponto percentual na Selic na pr\u00f3xima reuni\u00e3o do Comit\u00ea de Pol\u00edtica Monet\u00e1ria (Copom), marcada para os dias 4 e 5 de agosto, reflete a an\u00e1lise dos especialistas.<\/p>\n<p>\\n<\/p>\n<p>Al\u00e9m disso, o desempenho das a\u00e7\u00f5es foi bastante positivo, com setores como o financeiro, representado pelo Ita\u00fa Unibanco e B3, apresentando altas significativas. A forte valoriza\u00e7\u00e3o dos ativos de empresas sens\u00edveis \u00e0 taxa de juros, como Magazine Luiza e MRV, reflete um clima de esperan\u00e7a na recupera\u00e7\u00e3o econ\u00f4mica, que impacta diretamente os alagoanos, especialmente os investidores locais e pessoas que buscam entender como essas oscila\u00e7\u00f5es podem influenciar suas finan\u00e7as pessoais.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Ibovespa registrou um expressivo crescimento de quase 3% nesta sexta-feira (10), atingindo 177.866,37 pontos, um marco que n\u00e3o era alcan\u00e7ado desde maio. O aumento foi impulsionado por dados de infla\u00e7\u00e3o que renovaram as expectativas de uma poss\u00edvel redu\u00e7\u00e3o na taxa Selic em agosto. Neste contexto, a bolsa acumulou uma alta de 2,18% na semana, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3627,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[11],"tags":[],"class_list":["post-3628","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alagoas"],"_links":{"self":[{"href":"https:\/\/cnnbra.com.br\/al\/wp-json\/wp\/v2\/posts\/3628","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cnnbra.com.br\/al\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cnnbra.com.br\/al\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cnnbra.com.br\/al\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cnnbra.com.br\/al\/wp-json\/wp\/v2\/comments?post=3628"}],"version-history":[{"count":0,"href":"https:\/\/cnnbra.com.br\/al\/wp-json\/wp\/v2\/posts\/3628\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cnnbra.com.br\/al\/wp-json\/wp\/v2\/media\/3627"}],"wp:attachment":[{"href":"https:\/\/cnnbra.com.br\/al\/wp-json\/wp\/v2\/media?parent=3628"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cnnbra.com.br\/al\/wp-json\/wp\/v2\/categories?post=3628"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cnnbra.com.br\/al\/wp-json\/wp\/v2\/tags?post=3628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}